{"id":532,"count":5,"description":"","link":"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/","name":"CP Electronics","slug":"cp-electronics","taxonomy":"product_brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CP Electronics Archives | Holders Wireless Lighting Control<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CP Electronics Archives | Holders Wireless Lighting Control\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/\" \/>\n<meta property=\"og:site_name\" content=\"Holders Wireless Lighting Control\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/brand\\\/cp-electronics\\\/\",\"url\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/brand\\\/cp-electronics\\\/\",\"name\":\"CP Electronics Archives | Holders Wireless Lighting Control\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/brand\\\/cp-electronics\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/brand\\\/cp-electronics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"&#8962;\",\"item\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CP Electronics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/#website\",\"url\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/\",\"name\":\"Holders Wireless Lighting Control\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/#organization\",\"name\":\"Holders Technology Group\",\"url\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/logo_holders-technology.svg\",\"contentUrl\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/logo_holders-technology.svg\",\"width\":556,\"height\":66,\"caption\":\"Holders Technology Group\"},\"image\":{\"@id\":\"https:\\\/\\\/holderstechnology.com\\\/wireless-lighting-control\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CP Electronics Archives | Holders Wireless Lighting Control","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/","og_locale":"en_GB","og_type":"article","og_title":"CP Electronics Archives | Holders Wireless Lighting Control","og_url":"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/","og_site_name":"Holders Wireless Lighting Control","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/","url":"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/","name":"CP Electronics Archives | Holders Wireless Lighting Control","isPartOf":{"@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/#website"},"breadcrumb":{"@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/brand\/cp-electronics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"&#8962;","item":"https:\/\/holderstechnology.com\/wireless-lighting-control\/"},{"@type":"ListItem","position":2,"name":"CP Electronics"}]},{"@type":"WebSite","@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/#website","url":"https:\/\/holderstechnology.com\/wireless-lighting-control\/","name":"Holders Wireless Lighting Control","description":"","publisher":{"@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holderstechnology.com\/wireless-lighting-control\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/#organization","name":"Holders Technology Group","url":"https:\/\/holderstechnology.com\/wireless-lighting-control\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/#\/schema\/logo\/image\/","url":"https:\/\/holderstechnology.com\/wireless-lighting-control\/wp-content\/uploads\/sites\/3\/2024\/01\/logo_holders-technology.svg","contentUrl":"https:\/\/holderstechnology.com\/wireless-lighting-control\/wp-content\/uploads\/sites\/3\/2024\/01\/logo_holders-technology.svg","width":556,"height":66,"caption":"Holders Technology Group"},"image":{"@id":"https:\/\/holderstechnology.com\/wireless-lighting-control\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/holderstechnology.com\/wireless-lighting-control\/wp-json\/wp\/v2\/product_brand\/532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holderstechnology.com\/wireless-lighting-control\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/holderstechnology.com\/wireless-lighting-control\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/holderstechnology.com\/wireless-lighting-control\/wp-json\/wp\/v2\/product?product_brand=532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}